{"id":62,"count":2,"description":"","link":"https:\/\/www.jasonalder.com\/blog\/category\/projects\/shadanga-duo\/","name":"Shadanga Duo","slug":"shadanga-duo","taxonomy":"category","parent":10,"meta":[],"_links":{"self":[{"href":"https:\/\/www.jasonalder.com\/blog\/wp-json\/wp\/v2\/categories\/62"}],"collection":[{"href":"https:\/\/www.jasonalder.com\/blog\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.jasonalder.com\/blog\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/www.jasonalder.com\/blog\/wp-json\/wp\/v2\/categories\/10"}],"wp:post_type":[{"href":"https:\/\/www.jasonalder.com\/blog\/wp-json\/wp\/v2\/posts?categories=62"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}